{"id":4993,"date":"2020-11-20T11:49:49","date_gmt":"2020-11-20T10:49:49","guid":{"rendered":"https:\/\/beautytherapy.absolution-cosmetics.com\/?p=4993"},"modified":"2024-12-09T08:37:09","modified_gmt":"2024-12-09T07:37:09","slug":"diy-cotons-demaquillants-lavables","status":"publish","type":"post","link":"https:\/\/beautytherapy.absolution-cosmetics.com\/fr\/prendre-soin-de-sa-peau\/diy-cotons-demaquillants-lavables\/","title":{"rendered":"DIY\u202f: r\u00e9aliser ses propres cotons d\u00e9maquillants lavables"},"content":{"rendered":"<section class=\"block-grid-wrapper block-grid-for-core-paragraph\">\n      <div class=\"default-editor-content grid-for-core-paragraph container-fluid container-px-1\">\n        <div class=\"row row-cols-1 align-center\">\n          <div class=\"cell\">\n            \n<p class=\"has-text-align-center\"><strong>Si on vous dit d\u00e9maquillage, pensez-vous tout de suite \u00e0 ces petits ronds de cotons qu\u2019on rach\u00e8te inlassablement tous les mois&nbsp;et qu\u2019on jette&nbsp;apr\u00e8s usage\u202f? Si la r\u00e9ponse est oui,&nbsp;on a une tr\u00e8s bonne nouvelle pour vous, votre porte-monnaie et la plan\u00e8te\u202f!&nbsp;<\/strong><\/p>\n          <\/div>\n        <\/div>\n      <\/div>\n\n      <\/section>\n\n<section class=\"block-grid-wrapper block-grid-for-core-heading\">\n      <div class=\"default-editor-content grid-for-core-heading container-fluid container-px-1\">\n        <div class=\"row row-cols-1 align-center\">\n          <div class=\"cell\">\n            \n<h2 class=\"wp-block-heading\"><strong>Pourquoi les cotons jetables ne sont pas une solution&nbsp;?&nbsp;<\/strong>&nbsp;<\/h2>\n          <\/div>\n        <\/div>\n      <\/div>\n\n      <\/section>\n\n<section class=\"block-grid-wrapper block-grid-for-core-paragraph\">\n      <div class=\"default-editor-content grid-for-core-paragraph container-fluid container-px-1\">\n        <div class=\"row row-cols-1 align-center\">\n          <div class=\"cell\">\n            \n<p>Au-del\u00e0 du budget qu\u2019ils repr\u00e9sentent (environ&nbsp;50\u20ac par an&nbsp;si vous vous d\u00e9maquillez tous les jours), ils&nbsp;repr\u00e9sentent&nbsp;surtout&nbsp;un gros probl\u00e8me pour l\u2019\u00e9cologie.&nbsp;Pour produire 1kg de coton, il faut plus de 5000 litres d\u2019eau&nbsp;mais aussi une grande quantit\u00e9 de pesticides. Cela met en danger les personnes qui travaillent dans les cultures, et c\u2019est aussi une des causes principales de pollution des cours d\u2019eau dans les pays producteurs.&nbsp;Et pour les cotons jetables bio\u202f? Pas de pesticides,&nbsp;mais toujours beaucoup&nbsp;trop&nbsp;d\u2019eau&nbsp;pour un produit destin\u00e9 \u00e0 remplir notre poubelle de salle de bain.&nbsp;&nbsp;<\/p>\n          <\/div>\n        <\/div>\n      <\/div>\n\n      <\/section>\n\n<section class=\"block-grid-wrapper block-grid-for-core-paragraph\">\n      <div class=\"default-editor-content grid-for-core-paragraph container-fluid container-px-1\">\n        <div class=\"row row-cols-1 align-center\">\n          <div class=\"cell\">\n            \n<p>Alors on&nbsp;privil\u00e9gie&nbsp;le coton bio pour les v\u00eatements&nbsp;qu\u2019on aimera porter plusieurs ann\u00e9es,&nbsp;et on&nbsp;opte&nbsp;pour&nbsp;une alternative durable&nbsp;et&nbsp;tr\u00e8s&nbsp;\u00e9conomique&nbsp;pour se d\u00e9maquiller au&nbsp;quotidien.&nbsp;&nbsp;<\/p>\n          <\/div>\n        <\/div>\n      <\/div>\n\n      <\/section>\n\n<section class=\"block-grid-wrapper block-grid-for-core-heading\">\n      <div class=\"default-editor-content grid-for-core-heading container-fluid container-px-1\">\n        <div class=\"row row-cols-1 align-center\">\n          <div class=\"cell\">\n            \n<h2 class=\"wp-block-heading\"><strong>Quelle alternative aux cotons jetables\u202f?<\/strong>&nbsp;<\/h2>\n          <\/div>\n        <\/div>\n      <\/div>\n\n      <\/section>\n\n<section class=\"block-grid-wrapper block-grid-for-core-paragraph\">\n      <div class=\"default-editor-content grid-for-core-paragraph container-fluid container-px-1\">\n        <div class=\"row row-cols-1 align-center\">\n          <div class=\"cell\">\n            \n<p>Z\u00e9ro d\u00e9chet, \u00e9conomiques, \u00e9cologiques, plus doux pour la peau\u2026 Voil\u00e0 quelques&nbsp;bonnes&nbsp;raisons d\u2019adopter des cotons lavables&nbsp;pour vous d\u00e9maquiller au quotidien.&nbsp;En plus de vous durer plusieurs ann\u00e9es,&nbsp;ils peuvent&nbsp;aussi \u00eatre tr\u00e8s chic sur le bord du lavabo\u202fet rendre votre rituel&nbsp;de soin&nbsp;encore plus agr\u00e9able.&nbsp;&nbsp;<\/p>\n          <\/div>\n        <\/div>\n      <\/div>\n\n      <\/section>\n\n<section class=\"block-grid-wrapper block-grid-for-core-heading\">\n      <div class=\"default-editor-content grid-for-core-heading container-fluid container-px-1\">\n        <div class=\"row row-cols-1 align-center\">\n          <div class=\"cell\">\n            \n<h2 class=\"wp-block-heading\"><strong>O\u00f9 les trouver\u202f?&nbsp;<\/strong>&nbsp;<\/h2>\n          <\/div>\n        <\/div>\n      <\/div>\n\n      <\/section>\n\n<section class=\"block-grid-wrapper block-grid-for-core-paragraph\">\n      <div class=\"default-editor-content grid-for-core-paragraph container-fluid container-px-1\">\n        <div class=\"row row-cols-1 align-center\">\n          <div class=\"cell\">\n            \n<p>Si vous n\u2019\u00eates pas tr\u00e8s&nbsp;manuel.le, vous les trouverez facilement sur des sites comme&nbsp;Etsy&nbsp;(fabrication artisanale) ou&nbsp;dans&nbsp;des magasins&nbsp;z\u00e9ro d\u00e9chet. Si en revanche&nbsp;vous avez l\u2019\u00e2me cr\u00e9ative et une petite heure devant vous, c\u2019est l\u2019occasion de vous lancer dans la confection de vos propres cotons d\u00e9maquillants.&nbsp;&nbsp;<\/p>\n          <\/div>\n        <\/div>\n      <\/div>\n\n      <\/section>\n\n<section class=\"block-grid-wrapper block-grid-for-core-paragraph\">\n      <div class=\"default-editor-content grid-for-core-paragraph container-fluid container-px-1\">\n        <div class=\"row row-cols-1 align-center\">\n          <div class=\"cell\">\n            \n<p>L\u2019\u00e9quipe Absolution vous a pr\u00e9par\u00e9 un tutoriel simple et accessible aux&nbsp;d\u00e9butant.e.s. Si vous n\u2019avez pas de machine \u00e0 coudre, vous pouvez&nbsp;tout \u00e0 fait&nbsp;les r\u00e9aliser \u00e0 la main. Ce sera juste un peu plus long, mais c\u2019est aussi tr\u00e8s m\u00e9ditatif.&nbsp;&nbsp;<\/p>\n          <\/div>\n        <\/div>\n      <\/div>\n\n      <\/section>\n\n<section class=\"block-grid-wrapper block-grid-for-core-paragraph\">\n      <div class=\"default-editor-content grid-for-core-paragraph container-fluid container-px-1\">\n        <div class=\"row row-cols-1 align-center\">\n          <div class=\"cell\">\n            \n<p><strong>Temps de r\u00e9alisation<\/strong>\u202f: une&nbsp;heure&nbsp;<\/p>\n          <\/div>\n        <\/div>\n      <\/div>\n\n      <\/section>\n\n<section class=\"block-grid-wrapper block-grid-for-core-paragraph\">\n      <div class=\"default-editor-content grid-for-core-paragraph container-fluid container-px-1\">\n        <div class=\"row row-cols-1 align-center\">\n          <div class=\"cell\">\n            \n<p><strong>Niveau<\/strong>\u202f:&nbsp;d\u00e9butant.e&nbsp;<\/p>\n          <\/div>\n        <\/div>\n      <\/div>\n\n      <\/section>\n\n<section class=\"block-grid-wrapper block-grid-for-core-paragraph\">\n      <div class=\"default-editor-content grid-for-core-paragraph container-fluid container-px-1\">\n        <div class=\"row row-cols-1 align-center\">\n          <div class=\"cell\">\n            \n<p><strong>Mat\u00e9riel\u202fpour 3 cotons d\u2019environ 10&#215;10 cm<\/strong>&nbsp;<\/p>\n          <\/div>\n        <\/div>\n      <\/div>\n\n      <\/section>\n\n<section class=\"block-grid-wrapper block-grid-for-core-media-text\">\n      <div class=\"default-editor-content grid-for-core-media-text container-fluid container-px-1\">\n        <div class=\"row row-cols-1 align-center\">\n          <div class=\"cell\">\n            \n<div class=\"wp-block-media-text alignwide is-stacked-on-mobile\"><figure class=\"wp-block-media-text__media\"><img loading=\"lazy\" decoding=\"async\" width=\"931\" height=\"1024\" src=\"https:\/\/beautytherapy.absolution-cosmetics.com\/wp-content\/uploads\/2020\/11\/Mate\u0301riel_Coton-931x1024.png\" alt=\"\" class=\"wp-image-4996\" srcset=\"https:\/\/beautytherapy.absolution-cosmetics.com\/wp-content\/uploads\/2020\/11\/Mate\u0301riel_Coton-931x1024.png 931w, https:\/\/beautytherapy.absolution-cosmetics.com\/wp-content\/uploads\/2020\/11\/Mate\u0301riel_Coton-273x300.png 273w, https:\/\/beautytherapy.absolution-cosmetics.com\/wp-content\/uploads\/2020\/11\/Mate\u0301riel_Coton-768x845.png 768w, https:\/\/beautytherapy.absolution-cosmetics.com\/wp-content\/uploads\/2020\/11\/Mate\u0301riel_Coton-1396x1536.png 1396w, https:\/\/beautytherapy.absolution-cosmetics.com\/wp-content\/uploads\/2020\/11\/Mate\u0301riel_Coton-1861x2048.png 1861w, https:\/\/beautytherapy.absolution-cosmetics.com\/wp-content\/uploads\/2020\/11\/Mate\u0301riel_Coton-1080x1188.png 1080w, https:\/\/beautytherapy.absolution-cosmetics.com\/wp-content\/uploads\/2020\/11\/Mate\u0301riel_Coton-1280x1408.png 1280w, https:\/\/beautytherapy.absolution-cosmetics.com\/wp-content\/uploads\/2020\/11\/Mate\u0301riel_Coton-980x1078.png 980w, https:\/\/beautytherapy.absolution-cosmetics.com\/wp-content\/uploads\/2020\/11\/Mate\u0301riel_Coton-480x528.png 480w\" sizes=\"auto, (max-width: 931px) 100vw, 931px\" \/><\/figure><div class=\"wp-block-media-text__content\">\n<ul class=\"wp-block-list\" id=\"block-66288a3b-970b-4ad1-bee2-95f46a193541\"><li><strong>Une machine \u00e0 coudre&nbsp;<\/strong><\/li><li><strong>Une bobine de fil<\/strong> assorti \u00e0 votre tissu + <strong>une canette de fil blanc&nbsp;<\/strong><\/li><li><strong>3 carr\u00e9s de tissu&nbsp;de&nbsp;11&#215;11&nbsp;cm<\/strong>, avec le motif de votre choix. Pour une d\u00e9marche encore plus z\u00e9ro d\u00e9chet, vous pouvez utiliser des chutes de tissu ou&nbsp;upcycler&nbsp;une vieille chemise\/taie d\u2019oreiller.<\/li><li><strong>3 carr\u00e9s de tissu polaire de&nbsp;11&#215;11&nbsp;cm<\/strong>.&nbsp;On vous conseille le polaire de bambou&nbsp;certifi\u00e9 bio, plus doux pour la peau et plus \u00e9cologique&nbsp;que le coton.&nbsp;&nbsp;<\/li><li><strong>Une paire de ciseaux&nbsp;de couture<\/strong>&nbsp;<\/li><li><strong>Une r\u00e8gle<\/strong>&nbsp;<\/li><li><strong>Quelques \u00e9pingles<\/strong>&nbsp;<\/li><li><strong>Un fer \u00e0 repasser<\/strong>&nbsp;<\/li><\/ul>\n<\/div><\/div>\n          <\/div>\n        <\/div>\n      <\/div>\n\n      <\/section>\n\n<section class=\"block-grid-wrapper block-grid-for-core-spacer\">\n      <div class=\"default-editor-content grid-for-core-spacer container-fluid container-px-1\">\n        <div class=\"row row-cols-1 align-center\">\n          <div class=\"cell\">\n            \n<div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n          <\/div>\n        <\/div>\n      <\/div>\n\n      <\/section>\n\n<section class=\"block-grid-wrapper block-grid-for-core-paragraph\">\n      <div class=\"default-editor-content grid-for-core-paragraph container-fluid container-px-1\">\n        <div class=\"row row-cols-1 align-center\">\n          <div class=\"cell\">\n            \n<p><strong>Les \u00e9tapes\u202f:&nbsp;<\/strong>&nbsp;<\/p>\n          <\/div>\n        <\/div>\n      <\/div>\n\n      <\/section>\n\n<section class=\"block-grid-wrapper block-grid-for-core-paragraph\">\n      <div class=\"default-editor-content grid-for-core-paragraph container-fluid container-px-1\">\n        <div class=\"row row-cols-1 align-center\">\n          <div class=\"cell\">\n            \n<p>Avant de commencer, votre tissu doit \u00eatre propre et sec. S\u2019il est neuf, il est important de le passer en machine pour retirer l\u2019appr\u00eat qui le rend plus lisse et brillant.&nbsp;&nbsp;<\/p>\n          <\/div>\n        <\/div>\n      <\/div>\n\n      <\/section>\n\n<section class=\"block-grid-wrapper block-grid-for-core-list\">\n      <div class=\"default-editor-content grid-for-core-list container-fluid container-px-1\">\n        <div class=\"row row-cols-1 align-center\">\n          <div class=\"cell\">\n            \n<ol class=\"wp-block-list\"><li>Repassez&nbsp;vos&nbsp;tissus&nbsp;puis assemblez-les\u202f:&nbsp;un carr\u00e9 de tissu et un carr\u00e9 de polaire,&nbsp;endroit contre endroit.&nbsp;&nbsp;<\/li><\/ol>\n          <\/div>\n        <\/div>\n      <\/div>\n\n      <\/section>\n\n<section class=\"block-grid-wrapper block-grid-for-core-image\">\n      <div class=\"default-editor-content grid-for-core-image container-fluid container-px-1\">\n        <div class=\"row row-cols-1 align-center\">\n          <div class=\"cell\">\n            \n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/beautytherapy.absolution-cosmetics.com\/wp-content\/uploads\/2020\/11\/Etape-2--980x1024.png\" alt=\"\" class=\"wp-image-5000\" width=\"374\" height=\"390\" srcset=\"https:\/\/beautytherapy.absolution-cosmetics.com\/wp-content\/uploads\/2020\/11\/Etape-2--980x1024.png 980w, https:\/\/beautytherapy.absolution-cosmetics.com\/wp-content\/uploads\/2020\/11\/Etape-2--287x300.png 287w, https:\/\/beautytherapy.absolution-cosmetics.com\/wp-content\/uploads\/2020\/11\/Etape-2--768x802.png 768w, https:\/\/beautytherapy.absolution-cosmetics.com\/wp-content\/uploads\/2020\/11\/Etape-2--1470x1536.png 1470w, https:\/\/beautytherapy.absolution-cosmetics.com\/wp-content\/uploads\/2020\/11\/Etape-2--1961x2048.png 1961w, https:\/\/beautytherapy.absolution-cosmetics.com\/wp-content\/uploads\/2020\/11\/Etape-2--1080x1128.png 1080w, https:\/\/beautytherapy.absolution-cosmetics.com\/wp-content\/uploads\/2020\/11\/Etape-2--1280x1337.png 1280w, https:\/\/beautytherapy.absolution-cosmetics.com\/wp-content\/uploads\/2020\/11\/Etape-2--480x501.png 480w, https:\/\/beautytherapy.absolution-cosmetics.com\/wp-content\/uploads\/2020\/11\/Etape-2--24x24.png 24w\" sizes=\"auto, (max-width: 374px) 100vw, 374px\" \/><figcaption>2. Placez vos aiguilles pour&nbsp;maintenir les deux coupons de tissu (t\u00eate de l\u2019aiguille vers l\u2019ext\u00e9rieur)&nbsp;<\/figcaption><\/figure><\/div>\n          <\/div>\n        <\/div>\n      <\/div>\n\n      <\/section>\n\n<section class=\"block-grid-wrapper block-grid-for-core-columns\">\n      <div class=\"default-editor-content grid-for-core-columns container-fluid container-px-1\">\n        <div class=\"row row-cols-1 align-center\">\n          <div class=\"cell\">\n            \n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-9d6595d7 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/beautytherapy.absolution-cosmetics.com\/wp-content\/uploads\/2020\/11\/3-998x1024.png\" alt=\"\" class=\"wp-image-5002\" width=\"407\" height=\"417\" srcset=\"https:\/\/beautytherapy.absolution-cosmetics.com\/wp-content\/uploads\/2020\/11\/3-998x1024.png 998w, https:\/\/beautytherapy.absolution-cosmetics.com\/wp-content\/uploads\/2020\/11\/3-292x300.png 292w, https:\/\/beautytherapy.absolution-cosmetics.com\/wp-content\/uploads\/2020\/11\/3-768x788.png 768w, https:\/\/beautytherapy.absolution-cosmetics.com\/wp-content\/uploads\/2020\/11\/3-1496x1536.png 1496w, https:\/\/beautytherapy.absolution-cosmetics.com\/wp-content\/uploads\/2020\/11\/3-1995x2048.png 1995w, https:\/\/beautytherapy.absolution-cosmetics.com\/wp-content\/uploads\/2020\/11\/3-1080x1109.png 1080w, https:\/\/beautytherapy.absolution-cosmetics.com\/wp-content\/uploads\/2020\/11\/3-1280x1314.png 1280w, https:\/\/beautytherapy.absolution-cosmetics.com\/wp-content\/uploads\/2020\/11\/3-980x1006.png 980w, https:\/\/beautytherapy.absolution-cosmetics.com\/wp-content\/uploads\/2020\/11\/3-480x493.png 480w, https:\/\/beautytherapy.absolution-cosmetics.com\/wp-content\/uploads\/2020\/11\/3-45x45.png 45w, https:\/\/beautytherapy.absolution-cosmetics.com\/wp-content\/uploads\/2020\/11\/3-24x24.png 24w, https:\/\/beautytherapy.absolution-cosmetics.com\/wp-content\/uploads\/2020\/11\/3-48x48.png 48w\" sizes=\"auto, (max-width: 407px) 100vw, 407px\" \/><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/beautytherapy.absolution-cosmetics.com\/wp-content\/uploads\/2020\/11\/3-bis-1024x966.png\" alt=\"\" class=\"wp-image-5007\" width=\"436\" height=\"412\"\/><\/figure>\n<\/div>\n<\/div>\n          <\/div>\n        <\/div>\n      <\/div>\n\n      <\/section>\n\n<section class=\"block-grid-wrapper block-grid-for-core-list\">\n      <div class=\"default-editor-content grid-for-core-list container-fluid container-px-1\">\n        <div class=\"row row-cols-1 align-center\">\n          <div class=\"cell\">\n            \n<ol class=\"wp-block-list\" start=\"3\"><li>Commencez \u00e0 coudre\u00a0au\u00a0point droit selon le sch\u00e9ma ci-dessus, en veillant \u00e0 commencer et terminer par un point d\u2019arr\u00eat. Laissez 3-4 cm d\u2019ouverture.\u00a0\u00a0<\/li><\/ol>\n          <\/div>\n        <\/div>\n      <\/div>\n\n      <\/section>\n\n<section class=\"block-grid-wrapper block-grid-for-core-columns\">\n      <div class=\"default-editor-content grid-for-core-columns container-fluid container-px-1\">\n        <div class=\"row row-cols-1 align-center\">\n          <div class=\"cell\">\n            \n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-9d6595d7 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"2880\" height=\"3170\" src=\"https:\/\/beautytherapy.absolution-cosmetics.com\/wp-content\/uploads\/2020\/11\/4-930x1024.png\" alt=\"\" class=\"wp-image-5013\"\/><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/beautytherapy.absolution-cosmetics.com\/wp-content\/uploads\/2020\/11\/4-bis--1024x986.png\" alt=\"\" class=\"wp-image-5025\" width=\"404\" height=\"445\"\/><\/figure>\n<\/div>\n<\/div>\n          <\/div>\n        <\/div>\n      <\/div>\n\n      <\/section>\n\n<section class=\"block-grid-wrapper block-grid-for-core-list\">\n      <div class=\"default-editor-content grid-for-core-list container-fluid container-px-1\">\n        <div class=\"row row-cols-1 align-center\">\n          <div class=\"cell\">\n            \n<ol class=\"wp-block-list\" start=\"4\"><li>Une fois vos carr\u00e9s cousus ensemble, arrondissez les angles avec une paire de ciseaux, et coupez le tissu qui d\u00e9passe des coutures.&nbsp;&nbsp;<\/li><\/ol>\n          <\/div>\n        <\/div>\n      <\/div>\n\n      <\/section>\n\n<section class=\"block-grid-wrapper block-grid-for-core-image\">\n      <div class=\"default-editor-content grid-for-core-image container-fluid container-px-1\">\n        <div class=\"row row-cols-1 align-center\">\n          <div class=\"cell\">\n            \n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/beautytherapy.absolution-cosmetics.com\/wp-content\/uploads\/2020\/11\/5-766x1024.png\" alt=\"\" class=\"wp-image-5019\" width=\"391\" height=\"523\"\/><figcaption>5. Retournez votre travail en faisant passer un premier coin par l\u2019ouverture, puis les trois suivants.&nbsp;&nbsp;<\/figcaption><\/figure><\/div>\n          <\/div>\n        <\/div>\n      <\/div>\n\n      <\/section>\n\n<section class=\"block-grid-wrapper block-grid-for-core-image\">\n      <div class=\"default-editor-content grid-for-core-image container-fluid container-px-1\">\n        <div class=\"row row-cols-1 align-center\">\n          <div class=\"cell\">\n            \n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/beautytherapy.absolution-cosmetics.com\/wp-content\/uploads\/2020\/11\/6-1024x970.png\" alt=\"\" class=\"wp-image-5021\" width=\"391\" height=\"370\"\/><figcaption>6. \u00c0 l\u2019aide d\u2019une baguette ou d\u2019un stylo, repoussez les angles afin qu\u2019ils soient bien nets.&nbsp;&nbsp;<\/figcaption><\/figure><\/div>\n          <\/div>\n        <\/div>\n      <\/div>\n\n      <\/section>\n\n<section class=\"block-grid-wrapper block-grid-for-core-image\">\n      <div class=\"default-editor-content grid-for-core-image container-fluid container-px-1\">\n        <div class=\"row row-cols-1 align-center\">\n          <div class=\"cell\">\n            \n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/beautytherapy.absolution-cosmetics.com\/wp-content\/uploads\/2020\/11\/7--921x1024.png\" alt=\"\" class=\"wp-image-5029\" width=\"396\" height=\"440\"\/><figcaption>7. Effectuez une couture au point droit sur l\u2019ouverture en rabattant bien les tissus vers l\u2019int\u00e9rieur. N\u2019oubliez pas le point d\u2019arr\u00eat au d\u00e9but et \u00e0 la fin pour que la couture soit solide.&nbsp;&nbsp;<\/figcaption><\/figure><\/div>\n          <\/div>\n        <\/div>\n      <\/div>\n\n      <\/section>\n\n<section class=\"block-grid-wrapper block-grid-for-core-image\">\n      <div class=\"default-editor-content grid-for-core-image container-fluid container-px-1\">\n        <div class=\"row row-cols-1 align-center\">\n          <div class=\"cell\">\n            \n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/beautytherapy.absolution-cosmetics.com\/wp-content\/uploads\/2020\/11\/8-1024x982.png\" alt=\"\" class=\"wp-image-5031\" width=\"421\" height=\"404\"\/><figcaption>8. Passez un dernier coup de fer \u00e0 repasser, et votre coton est pr\u00eat\u202f!&nbsp;<\/figcaption><\/figure><\/div>\n          <\/div>\n        <\/div>\n      <\/div>\n\n      <\/section>\n\n<section class=\"block-grid-wrapper block-grid-for-core-paragraph\">\n      <div class=\"default-editor-content grid-for-core-paragraph container-fluid container-px-1\">\n        <div class=\"row row-cols-1 align-center\">\n          <div class=\"cell\">\n            \n<p>Bravo, vous \u00eates&nbsp;pr\u00eat.e&nbsp;\u00e0 \u00e9conomiser des milliers de litres d\u2019eau et de pesticides, sans compter les \u00e9conomies que vous pourrez d\u00e9penser dans un bon restaurant, une pi\u00e8ce de mode \u00e9thique ou un soin Absolution\u202f.&nbsp;&nbsp;<\/p>\n          <\/div>\n        <\/div>\n      <\/div>\n\n      <\/section>\n\n<section class=\"block-grid-wrapper block-grid-for-core-paragraph\">\n      <div class=\"default-editor-content grid-for-core-paragraph container-fluid container-px-1\">\n        <div class=\"row row-cols-1 align-center\">\n          <div class=\"cell\">\n            \n<p>Pour l\u2019entretien, il suffit de frotter votre coton avec un peu de savon de Marseille apr\u00e8s votre d\u00e9maquillage, puis de le mettre en machine avec votre linge habituel. Et si vos cotons grisent avec le temps, plongez-les dans de l\u2019eau bouillante avec une cuill\u00e8re \u00e0 soupe de&nbsp;percarbonate&nbsp;de soude pendant 1h.&nbsp;Cette astuce permet de d\u00e9tacher tous les tissus et de leur redonner de l\u2019\u00e9clat sans produits chimiques.&nbsp;&nbsp;<\/p>\n          <\/div>\n        <\/div>\n      <\/div>\n\n      <\/section>\n\n<section class=\"block-grid-wrapper block-grid-for-core-paragraph\">\n      <div class=\"default-editor-content grid-for-core-paragraph container-fluid container-px-1\">\n        <div class=\"row row-cols-1 align-center\">\n          <div class=\"cell\">\n            \n<p>On vous souhaite un&nbsp;beau&nbsp;moment de couture, et&nbsp;on a h\u00e2te de voir vos cr\u00e9ations\u202f!&nbsp;&nbsp;<\/p>\n          <\/div>\n        <\/div>\n      <\/div>\n\n      <\/section>\n\n<section class=\"block-grid-wrapper block-grid-for-core-paragraph\">\n      <div class=\"default-editor-content grid-for-core-paragraph container-fluid container-px-1\">\n        <div class=\"row row-cols-1 align-center\">\n          <div class=\"cell\">\n            \n<p>N\u2019h\u00e9sitez pas&nbsp;\u00e0&nbsp;nous taguer, on se fera une joie de les repartager :&nbsp;<a href=\"https:\/\/www.instagram.com\/accounts\/login\/?next=https%3A%2F%2Fwww.instagram.com%2Fbeauty_therapy_absolution%2F&amp;is_from_rle\" target=\"_blank\" rel=\"noreferrer noopener\">@beauty_therapy_absolution<\/a>&nbsp;et <strong>#mybeautytherapy.&nbsp;&nbsp;<\/strong><\/p>\n          <\/div>\n        <\/div>\n      <\/div>\n\n      <\/section>","protected":false},"excerpt":{"rendered":"<p>Si on vous dit d\u00e9maquillage, pensez-vous tout de suite \u00e0 ces petits ronds de cotons qu\u2019on rach\u00e8te inlassablement tous les mois&nbsp;et qu\u2019on jette&nbsp;apr\u00e8s usage\u202f? Si la r\u00e9ponse est oui,&nbsp;on a une tr\u00e8s bonne nouvelle pour vous, votre porte-monnaie et la plan\u00e8te\u202f!&nbsp; Pourquoi les cotons jetables ne sont pas une solution&nbsp;?&nbsp;&nbsp; Au-del\u00e0 du budget qu\u2019ils repr\u00e9sentent [&hellip;]<\/p>\n","protected":false},"author":24,"featured_media":5034,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[995,997,992,1016,1012,990],"tags":[1227,1212,1229],"class_list":["post-4993","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-bien-etre","category-bien-etre-et-beaute","category-bons-gestes","category-eco-responsabilite","category-notre-actualite","category-prendre-soin-de-sa-peau","tag-diy","tag-ecologie","tag-soin-de-la-peau"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>DIY\u202f: r\u00e9aliser ses propres cotons d\u00e9maquillants lavables - Beauty Therapy<\/title>\n<meta name=\"description\" content=\"On a une tr\u00e8s bonne nouvelle pour votre porte-monnaie et la plan\u00e8te\u202f! L\u2019\u00e9quipe Absolution vous a pr\u00e9par\u00e9 un tutoriel simple et accessible aux d\u00e9butant.e.s. pour r\u00e9aliser vos propres cotons d\u00e9maquillants lavables.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/beautytherapy.absolution-cosmetics.com\/fr\/prendre-soin-de-sa-peau\/diy-cotons-demaquillants-lavables\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"DIY\u202f: r\u00e9aliser ses propres cotons d\u00e9maquillants lavables - Beauty Therapy\" \/>\n<meta property=\"og:description\" content=\"On a une tr\u00e8s bonne nouvelle pour votre porte-monnaie et la plan\u00e8te\u202f! L\u2019\u00e9quipe Absolution vous a pr\u00e9par\u00e9 un tutoriel simple et accessible aux d\u00e9butant.e.s. pour r\u00e9aliser vos propres cotons d\u00e9maquillants lavables.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/beautytherapy.absolution-cosmetics.com\/fr\/prendre-soin-de-sa-peau\/diy-cotons-demaquillants-lavables\/\" \/>\n<meta property=\"og:site_name\" content=\"Beauty Therapy\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/absolutioncosmetics\" \/>\n<meta property=\"article:published_time\" content=\"2020-11-20T10:49:49+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-12-09T07:37:09+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/beautytherapy.absolution-cosmetics.com\/wp-content\/uploads\/2020\/11\/Tuto-Coton.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1500\" \/>\n\t<meta property=\"og:image:height\" content=\"1000\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Edito Beauty Therapy\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Edito Beauty Therapy\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/beautytherapy.absolution-cosmetics.com\\\/fr\\\/prendre-soin-de-sa-peau\\\/diy-cotons-demaquillants-lavables\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/beautytherapy.absolution-cosmetics.com\\\/fr\\\/prendre-soin-de-sa-peau\\\/diy-cotons-demaquillants-lavables\\\/\"},\"author\":{\"name\":\"Edito Beauty Therapy\",\"@id\":\"https:\\\/\\\/beautytherapy.absolution-cosmetics.com\\\/fr\\\/#\\\/schema\\\/person\\\/39fa4ed518c548c2f2b7d6a399786b66\"},\"headline\":\"DIY\u202f: r\u00e9aliser ses propres cotons d\u00e9maquillants lavables\",\"datePublished\":\"2020-11-20T10:49:49+00:00\",\"dateModified\":\"2024-12-09T07:37:09+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/beautytherapy.absolution-cosmetics.com\\\/fr\\\/prendre-soin-de-sa-peau\\\/diy-cotons-demaquillants-lavables\\\/\"},\"wordCount\":978,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/beautytherapy.absolution-cosmetics.com\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/beautytherapy.absolution-cosmetics.com\\\/fr\\\/prendre-soin-de-sa-peau\\\/diy-cotons-demaquillants-lavables\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/beautytherapy.absolution-cosmetics.com\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/Tuto-Coton.png\",\"keywords\":[\"DIY\",\"Ecologie\",\"Soins de la peau\"],\"articleSection\":[\"Bien-\u00eatre\",\"Bien-\u00eatre et beaut\u00e9\",\"Bons gestes\",\"Eco-responsabilit\u00e9\",\"Notre actualit\u00e9\",\"Prendre soin de sa peau\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/beautytherapy.absolution-cosmetics.com\\\/fr\\\/prendre-soin-de-sa-peau\\\/diy-cotons-demaquillants-lavables\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/beautytherapy.absolution-cosmetics.com\\\/fr\\\/prendre-soin-de-sa-peau\\\/diy-cotons-demaquillants-lavables\\\/\",\"url\":\"https:\\\/\\\/beautytherapy.absolution-cosmetics.com\\\/fr\\\/prendre-soin-de-sa-peau\\\/diy-cotons-demaquillants-lavables\\\/\",\"name\":\"DIY\u202f: r\u00e9aliser ses propres cotons d\u00e9maquillants lavables - Beauty Therapy\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/beautytherapy.absolution-cosmetics.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/beautytherapy.absolution-cosmetics.com\\\/fr\\\/prendre-soin-de-sa-peau\\\/diy-cotons-demaquillants-lavables\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/beautytherapy.absolution-cosmetics.com\\\/fr\\\/prendre-soin-de-sa-peau\\\/diy-cotons-demaquillants-lavables\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/beautytherapy.absolution-cosmetics.com\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/Tuto-Coton.png\",\"datePublished\":\"2020-11-20T10:49:49+00:00\",\"dateModified\":\"2024-12-09T07:37:09+00:00\",\"description\":\"On a une tr\u00e8s bonne nouvelle pour votre porte-monnaie et la plan\u00e8te\u202f! L\u2019\u00e9quipe Absolution vous a pr\u00e9par\u00e9 un tutoriel simple et accessible aux d\u00e9butant.e.s. pour r\u00e9aliser vos propres cotons d\u00e9maquillants lavables.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/beautytherapy.absolution-cosmetics.com\\\/fr\\\/prendre-soin-de-sa-peau\\\/diy-cotons-demaquillants-lavables\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/beautytherapy.absolution-cosmetics.com\\\/fr\\\/prendre-soin-de-sa-peau\\\/diy-cotons-demaquillants-lavables\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/beautytherapy.absolution-cosmetics.com\\\/fr\\\/prendre-soin-de-sa-peau\\\/diy-cotons-demaquillants-lavables\\\/#primaryimage\",\"url\":\"https:\\\/\\\/beautytherapy.absolution-cosmetics.com\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/Tuto-Coton.png\",\"contentUrl\":\"https:\\\/\\\/beautytherapy.absolution-cosmetics.com\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/Tuto-Coton.png\",\"width\":1500,\"height\":1000},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/beautytherapy.absolution-cosmetics.com\\\/fr\\\/prendre-soin-de-sa-peau\\\/diy-cotons-demaquillants-lavables\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/beautytherapy.absolution-cosmetics.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Bien-\u00eatre\",\"item\":\"https:\\\/\\\/beautytherapy.absolution-cosmetics.com\\\/fr\\\/bien-etre\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Bien-\u00eatre et beaut\u00e9\",\"item\":\"https:\\\/\\\/beautytherapy.absolution-cosmetics.com\\\/fr\\\/bien-etre\\\/bien-etre-et-beaute\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"DIY\u202f: r\u00e9aliser ses propres cotons d\u00e9maquillants lavables\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/beautytherapy.absolution-cosmetics.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/beautytherapy.absolution-cosmetics.com\\\/fr\\\/\",\"name\":\"Beauty Therapy\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/beautytherapy.absolution-cosmetics.com\\\/fr\\\/#organization\"},\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/beautytherapy.absolution-cosmetics.com\\\/fr\\\/#organization\",\"name\":\"Beauty Therapy\",\"url\":\"https:\\\/\\\/beautytherapy.absolution-cosmetics.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/beautytherapy.absolution-cosmetics.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/beautytherapy.absolution-cosmetics.com\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/beauty-therapy-logo.png\",\"contentUrl\":\"https:\\\/\\\/beautytherapy.absolution-cosmetics.com\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/beauty-therapy-logo.png\",\"width\":424,\"height\":212,\"caption\":\"Beauty Therapy\"},\"image\":{\"@id\":\"https:\\\/\\\/beautytherapy.absolution-cosmetics.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/beautytherapy.absolution-cosmetics.com\\\/fr\\\/#\\\/schema\\\/person\\\/39fa4ed518c548c2f2b7d6a399786b66\",\"name\":\"Edito Beauty Therapy\",\"description\":\"L\u2019objectif d\u2019Absolution est \u00e0 la fois tout simple et merveilleusement complexe : retrouver la Beaut\u00e9 ! Celle du monde qui nous entoure, celle du monde que l\u2019on contient... celle qui se cache dans votre reflet le matin ! Les soins Absolution effacent les scories de nos vies d\u2019urbains : chaque jour ils offrent \u00e0 notre peau un retour \u00e0 sa beaut\u00e9 originelle en restaurant son \u00e9cosyst\u00e8me naturel et en l\u2019amenant \u00e0 son \u00e9tat optimum. \u00c9labor\u00e9e \u00e0 partir d\u2019extraits v\u00e9g\u00e9taux certifi\u00e9s bio ou sauvages, de min\u00e9raux et de vitamines, Absolution allie d\u00e9licatesse des textures et des senteurs, simplicit\u00e9 d\u2019utilisation et totale efficacit\u00e9 des formules. Absolution c\u2019est aussi une volont\u00e9 : celle de transmettre une fa\u00e7on de voir le monde qui fait \u00e9merger la beaut\u00e9 partout o\u00f9 elle est. Partagez-la avec nous ! @absolution_cosmetics #absolutioncosmetics #retrouverlabeaut\u00e9\",\"sameAs\":[\"https:\\\/\\\/www.absolution-cosmetics.com\\\/fr\\\/\",\"https:\\\/\\\/www.facebook.com\\\/absolutioncosmetics\",\"https:\\\/\\\/www.instagram.com\\\/absolution_cosmetics\\\/\"],\"url\":\"https:\\\/\\\/beautytherapy.absolution-cosmetics.com\\\/fr\\\/author\\\/l-equipe-absolution\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"DIY\u202f: r\u00e9aliser ses propres cotons d\u00e9maquillants lavables - Beauty Therapy","description":"On a une tr\u00e8s bonne nouvelle pour votre porte-monnaie et la plan\u00e8te\u202f! L\u2019\u00e9quipe Absolution vous a pr\u00e9par\u00e9 un tutoriel simple et accessible aux d\u00e9butant.e.s. pour r\u00e9aliser vos propres cotons d\u00e9maquillants lavables.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/beautytherapy.absolution-cosmetics.com\/fr\/prendre-soin-de-sa-peau\/diy-cotons-demaquillants-lavables\/","og_locale":"fr_FR","og_type":"article","og_title":"DIY\u202f: r\u00e9aliser ses propres cotons d\u00e9maquillants lavables - Beauty Therapy","og_description":"On a une tr\u00e8s bonne nouvelle pour votre porte-monnaie et la plan\u00e8te\u202f! L\u2019\u00e9quipe Absolution vous a pr\u00e9par\u00e9 un tutoriel simple et accessible aux d\u00e9butant.e.s. pour r\u00e9aliser vos propres cotons d\u00e9maquillants lavables.","og_url":"https:\/\/beautytherapy.absolution-cosmetics.com\/fr\/prendre-soin-de-sa-peau\/diy-cotons-demaquillants-lavables\/","og_site_name":"Beauty Therapy","article_author":"https:\/\/www.facebook.com\/absolutioncosmetics","article_published_time":"2020-11-20T10:49:49+00:00","article_modified_time":"2024-12-09T07:37:09+00:00","og_image":[{"width":1500,"height":1000,"url":"https:\/\/beautytherapy.absolution-cosmetics.com\/wp-content\/uploads\/2020\/11\/Tuto-Coton.png","type":"image\/png"}],"author":"Edito Beauty Therapy","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Edito Beauty Therapy","Dur\u00e9e de lecture estim\u00e9e":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/beautytherapy.absolution-cosmetics.com\/fr\/prendre-soin-de-sa-peau\/diy-cotons-demaquillants-lavables\/#article","isPartOf":{"@id":"https:\/\/beautytherapy.absolution-cosmetics.com\/fr\/prendre-soin-de-sa-peau\/diy-cotons-demaquillants-lavables\/"},"author":{"name":"Edito Beauty Therapy","@id":"https:\/\/beautytherapy.absolution-cosmetics.com\/fr\/#\/schema\/person\/39fa4ed518c548c2f2b7d6a399786b66"},"headline":"DIY\u202f: r\u00e9aliser ses propres cotons d\u00e9maquillants lavables","datePublished":"2020-11-20T10:49:49+00:00","dateModified":"2024-12-09T07:37:09+00:00","mainEntityOfPage":{"@id":"https:\/\/beautytherapy.absolution-cosmetics.com\/fr\/prendre-soin-de-sa-peau\/diy-cotons-demaquillants-lavables\/"},"wordCount":978,"commentCount":0,"publisher":{"@id":"https:\/\/beautytherapy.absolution-cosmetics.com\/fr\/#organization"},"image":{"@id":"https:\/\/beautytherapy.absolution-cosmetics.com\/fr\/prendre-soin-de-sa-peau\/diy-cotons-demaquillants-lavables\/#primaryimage"},"thumbnailUrl":"https:\/\/beautytherapy.absolution-cosmetics.com\/wp-content\/uploads\/2020\/11\/Tuto-Coton.png","keywords":["DIY","Ecologie","Soins de la peau"],"articleSection":["Bien-\u00eatre","Bien-\u00eatre et beaut\u00e9","Bons gestes","Eco-responsabilit\u00e9","Notre actualit\u00e9","Prendre soin de sa peau"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/beautytherapy.absolution-cosmetics.com\/fr\/prendre-soin-de-sa-peau\/diy-cotons-demaquillants-lavables\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/beautytherapy.absolution-cosmetics.com\/fr\/prendre-soin-de-sa-peau\/diy-cotons-demaquillants-lavables\/","url":"https:\/\/beautytherapy.absolution-cosmetics.com\/fr\/prendre-soin-de-sa-peau\/diy-cotons-demaquillants-lavables\/","name":"DIY\u202f: r\u00e9aliser ses propres cotons d\u00e9maquillants lavables - Beauty Therapy","isPartOf":{"@id":"https:\/\/beautytherapy.absolution-cosmetics.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/beautytherapy.absolution-cosmetics.com\/fr\/prendre-soin-de-sa-peau\/diy-cotons-demaquillants-lavables\/#primaryimage"},"image":{"@id":"https:\/\/beautytherapy.absolution-cosmetics.com\/fr\/prendre-soin-de-sa-peau\/diy-cotons-demaquillants-lavables\/#primaryimage"},"thumbnailUrl":"https:\/\/beautytherapy.absolution-cosmetics.com\/wp-content\/uploads\/2020\/11\/Tuto-Coton.png","datePublished":"2020-11-20T10:49:49+00:00","dateModified":"2024-12-09T07:37:09+00:00","description":"On a une tr\u00e8s bonne nouvelle pour votre porte-monnaie et la plan\u00e8te\u202f! L\u2019\u00e9quipe Absolution vous a pr\u00e9par\u00e9 un tutoriel simple et accessible aux d\u00e9butant.e.s. pour r\u00e9aliser vos propres cotons d\u00e9maquillants lavables.","breadcrumb":{"@id":"https:\/\/beautytherapy.absolution-cosmetics.com\/fr\/prendre-soin-de-sa-peau\/diy-cotons-demaquillants-lavables\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/beautytherapy.absolution-cosmetics.com\/fr\/prendre-soin-de-sa-peau\/diy-cotons-demaquillants-lavables\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/beautytherapy.absolution-cosmetics.com\/fr\/prendre-soin-de-sa-peau\/diy-cotons-demaquillants-lavables\/#primaryimage","url":"https:\/\/beautytherapy.absolution-cosmetics.com\/wp-content\/uploads\/2020\/11\/Tuto-Coton.png","contentUrl":"https:\/\/beautytherapy.absolution-cosmetics.com\/wp-content\/uploads\/2020\/11\/Tuto-Coton.png","width":1500,"height":1000},{"@type":"BreadcrumbList","@id":"https:\/\/beautytherapy.absolution-cosmetics.com\/fr\/prendre-soin-de-sa-peau\/diy-cotons-demaquillants-lavables\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/beautytherapy.absolution-cosmetics.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Bien-\u00eatre","item":"https:\/\/beautytherapy.absolution-cosmetics.com\/fr\/bien-etre\/"},{"@type":"ListItem","position":3,"name":"Bien-\u00eatre et beaut\u00e9","item":"https:\/\/beautytherapy.absolution-cosmetics.com\/fr\/bien-etre\/bien-etre-et-beaute\/"},{"@type":"ListItem","position":4,"name":"DIY\u202f: r\u00e9aliser ses propres cotons d\u00e9maquillants lavables"}]},{"@type":"WebSite","@id":"https:\/\/beautytherapy.absolution-cosmetics.com\/fr\/#website","url":"https:\/\/beautytherapy.absolution-cosmetics.com\/fr\/","name":"Beauty Therapy","description":"","publisher":{"@id":"https:\/\/beautytherapy.absolution-cosmetics.com\/fr\/#organization"},"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/beautytherapy.absolution-cosmetics.com\/fr\/#organization","name":"Beauty Therapy","url":"https:\/\/beautytherapy.absolution-cosmetics.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/beautytherapy.absolution-cosmetics.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/beautytherapy.absolution-cosmetics.com\/wp-content\/uploads\/2020\/02\/beauty-therapy-logo.png","contentUrl":"https:\/\/beautytherapy.absolution-cosmetics.com\/wp-content\/uploads\/2020\/02\/beauty-therapy-logo.png","width":424,"height":212,"caption":"Beauty Therapy"},"image":{"@id":"https:\/\/beautytherapy.absolution-cosmetics.com\/fr\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/beautytherapy.absolution-cosmetics.com\/fr\/#\/schema\/person\/39fa4ed518c548c2f2b7d6a399786b66","name":"Edito Beauty Therapy","description":"L\u2019objectif d\u2019Absolution est \u00e0 la fois tout simple et merveilleusement complexe : retrouver la Beaut\u00e9 ! Celle du monde qui nous entoure, celle du monde que l\u2019on contient... celle qui se cache dans votre reflet le matin ! Les soins Absolution effacent les scories de nos vies d\u2019urbains : chaque jour ils offrent \u00e0 notre peau un retour \u00e0 sa beaut\u00e9 originelle en restaurant son \u00e9cosyst\u00e8me naturel et en l\u2019amenant \u00e0 son \u00e9tat optimum. \u00c9labor\u00e9e \u00e0 partir d\u2019extraits v\u00e9g\u00e9taux certifi\u00e9s bio ou sauvages, de min\u00e9raux et de vitamines, Absolution allie d\u00e9licatesse des textures et des senteurs, simplicit\u00e9 d\u2019utilisation et totale efficacit\u00e9 des formules. Absolution c\u2019est aussi une volont\u00e9 : celle de transmettre une fa\u00e7on de voir le monde qui fait \u00e9merger la beaut\u00e9 partout o\u00f9 elle est. Partagez-la avec nous ! @absolution_cosmetics #absolutioncosmetics #retrouverlabeaut\u00e9","sameAs":["https:\/\/www.absolution-cosmetics.com\/fr\/","https:\/\/www.facebook.com\/absolutioncosmetics","https:\/\/www.instagram.com\/absolution_cosmetics\/"],"url":"https:\/\/beautytherapy.absolution-cosmetics.com\/fr\/author\/l-equipe-absolution\/"}]}},"_links":{"self":[{"href":"https:\/\/beautytherapy.absolution-cosmetics.com\/fr\/wp-json\/wp\/v2\/posts\/4993","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/beautytherapy.absolution-cosmetics.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/beautytherapy.absolution-cosmetics.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/beautytherapy.absolution-cosmetics.com\/fr\/wp-json\/wp\/v2\/users\/24"}],"replies":[{"embeddable":true,"href":"https:\/\/beautytherapy.absolution-cosmetics.com\/fr\/wp-json\/wp\/v2\/comments?post=4993"}],"version-history":[{"count":3,"href":"https:\/\/beautytherapy.absolution-cosmetics.com\/fr\/wp-json\/wp\/v2\/posts\/4993\/revisions"}],"predecessor-version":[{"id":24065,"href":"https:\/\/beautytherapy.absolution-cosmetics.com\/fr\/wp-json\/wp\/v2\/posts\/4993\/revisions\/24065"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/beautytherapy.absolution-cosmetics.com\/fr\/wp-json\/wp\/v2\/media\/5034"}],"wp:attachment":[{"href":"https:\/\/beautytherapy.absolution-cosmetics.com\/fr\/wp-json\/wp\/v2\/media?parent=4993"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/beautytherapy.absolution-cosmetics.com\/fr\/wp-json\/wp\/v2\/categories?post=4993"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/beautytherapy.absolution-cosmetics.com\/fr\/wp-json\/wp\/v2\/tags?post=4993"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}